{"id":7608,"date":"2019-04-26T13:40:17","date_gmt":"2019-04-26T13:40:17","guid":{"rendered":"http:\/\/palomapieldearena.es\/?p=7608\/"},"modified":"2019-04-26T13:40:17","modified_gmt":"2019-04-26T13:40:17","slug":"dakini-esta-noche","status":"publish","type":"post","link":"https:\/\/palomapieldearena.es\/es\/dakini-esta-noche\/","title":{"rendered":"Dakini esta noche"},"content":{"rendered":"<p>Comienza un fin de semana lleno de danza, para celebrar que a trav\u00e9s de este arte queremos hacer llegar emociones, pensamientos, experiencias y compartir desde el presente.<\/p>\n<p>Esta noche Dakini en la Casona de San Luis en Santa \u00darsula (Tenerife).<\/p>\n<p>El domingo Dulces Bestias en Teatro Guiniguada (Gran Canaria).<\/p>\n<p>Les esperamos!!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comienza un fin de semana lleno de danza, para celebrar que a trav\u00e9s de este arte queremos hacer llegar emociones, pensamientos, experiencias y compartir desde el presente. Esta noche Dakini [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7609,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"_links":{"self":[{"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/posts\/7608"}],"collection":[{"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/comments?post=7608"}],"version-history":[{"count":1,"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/posts\/7608\/revisions"}],"predecessor-version":[{"id":7610,"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/posts\/7608\/revisions\/7610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/media\/7609"}],"wp:attachment":[{"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/media?parent=7608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/categories?post=7608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palomapieldearena.es\/es\/wp-json\/wp\/v2\/tags?post=7608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}